{"id":35939,"date":"2021-08-26T09:59:41","date_gmt":"2021-08-26T07:59:41","guid":{"rendered":"https:\/\/tsisl.es\/?p=35939"},"modified":"2022-04-11T11:18:10","modified_gmt":"2022-04-11T09:18:10","slug":"sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica","status":"publish","type":"post","link":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/","title":{"rendered":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento.<\/p>\n<p style=\"text-align: justify;\">Meggitt SA es reconocida por sus m\u00e1s altos est\u00e1ndares de calidad, disponiendo de certificaciones regulares desde la primera certificaci\u00f3n ISO 9000 all\u00e1 por 1995. Los certificados de gesti\u00f3n ambiental fueron otorgados por AFNOR Certification. Adem\u00e1s, para ciertos productos espec\u00edficos dispone de <strong>certificaci\u00f3n Ex<\/strong> que permite puedan usarse en \u00e1reas peligrosas (atm\u00f3sferas potencialmente explosivas), por ejemplo, instaladas en turbinas de gas. Algunos tienen <strong>certificaci\u00f3n de seguridad SIL<\/strong> para que puedan utilizarse en aplicaciones relacionadas con la seguridad (contextos de seguridad funcional), por ejemplo, sistemas de protecci\u00f3n cr\u00edtica.<\/p>\n<p style=\"text-align: justify;\">La amplia gama de sensores y cadenas de medida (Vibraci\u00f3n Absoluta, Presi\u00f3n Din\u00e1mica, Air Gap, y velocidad y vibraci\u00f3n relativa) se pueden utilizar con nuestro sistema de monitorizaci\u00f3n (VM 600 y\/o Vibrosmart) junto con el software Vibrosight (o de terceros sistemas) con el fin de proporcionar soluciones completas para la vigilancia y protecci\u00f3n de maquinaria y procesos cr\u00edticos. Desde ambientes est\u00e1ndar ambientes a condiciones extremas.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35940\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2022\/03\/FOTO-1-1-1024x522.jpg\" alt=\"\" width=\"840\" height=\"429\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-35942\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2022\/03\/FOTO-2-1024x514.jpg\" alt=\"\" width=\"910\" height=\"457\" \/><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sistemas-de-monitorizacion-y-proteccion\/sistema-vm600\/\">Sistema VM600 | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\">El portoflio de Vibrometer esta especializado en productos y soluciones para la protecci\u00f3n de maquinaria y monitorizaci\u00f3n de maquinaria rotativa cr\u00edtica como pueden ser Hidroturbinas, Turbinas de gas y vapor&#8230; La <strong>serie CA<\/strong> de sensores de vibraci\u00f3n son de alta temperatura (hasta 700\u00baC), aceler\u00f3metros piezoel\u00e9ctricos dise\u00f1ados para realizar mediciones de largos per\u00edodos y seguimiento de la vibraci\u00f3n absoluta en la mayor\u00eda de ambientes con condiciones severas de medida.<\/p>\n<p style=\"text-align: justify;\">Se requiere un acondicionador de se\u00f1al IPC externo para convertir la carga de bajo nivel, se\u00f1al (pC \/ g) emitida por un sensor CA en una se\u00f1al de corriente o voltaje adecuada para transmisi\u00f3n al sistema de monitorizaci\u00f3n. Esta separaci\u00f3n de la electr\u00f3nica permite un alto rendimiento del sensor a temperaturas m\u00e1s altas. Cabe destacar que son equipos adecuados para su uso en aplicaciones relacionados con la seguridad, que utilizan cadenas de medida SIL 2.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/sensors-and-signal-conditioners\/high-temperature-vibration-sensors\/ca202-piezoelectric-accelerometer\/\">CA202 piezoelectric accelerometer &#8211; Vibro-meter Catalogue (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/IPC707_product_overview-en.pdf\">IPC707 signal conditioner product overview (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/sensors-and-signal-conditioners\/other\/gsi127-galvanic-separation-unit\/\">GSI127 galvanic separation unit &#8211; Vibro-meter Catalogue (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Los sensores de vibraci\u00f3n con electr\u00f3nica integrada se usan en aplicaciones que no requieren las capacidades para altas temperaturas de la serie CA.<\/p>\n<p style=\"text-align: justify;\">La <strong>serie CE<\/strong> de sensores son aceler\u00f3metros piezoel\u00e9ctricos que vienen con componentes electr\u00f3nicos integrados para aplicaciones de temperaturas m\u00e1s altas o electr\u00f3nica integrada para aplicaciones de baja temperatura, sin necesidad de acondicionadores de se\u00f1al y cableado m\u00e1s sencillo, en versiones est\u00e1ndar y Ex certificadas. Estos sensores son adecuados para la medici\u00f3n y monitorizaci\u00f3n de vibraciones en entornos hostiles, como turbinas de gas o vapor, compresores, bombas y ventiladores.<\/p>\n<p style=\"text-align: justify;\">El <strong>SE120<\/strong> es un aceler\u00f3metro piezorresistivo de alta sensibilidad adecuado para medici\u00f3n y monitorizaci\u00f3n de vibraciones a frecuencias m\u00e1s bajas en condiciones extremas, como turbinas hidr\u00e1ulicas y ventiladores.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/catalogue.meggittsensing.com\/wp-content\/uploads\/2021\/03\/datasheets_DS_SE120-en.pdf\">DS_SE120-en.fm (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Los sensores de vibraciones con salida de velocidad se pueden usar para el control de vibraciones de maquinaria rotativa de baja velocidad, midiendo vibraciones absolutas a baja frecuencia, en turbinas hidr\u00e1ulicas o en aplicaciones de ventiladores. El sensor de velocidad dise\u00f1ado de acuerdo con el principio de bobina m\u00f3vil proporciona una alta relaci\u00f3n se\u00f1al \/ ruido en el rango de baja frecuencia.<\/p>\n<p style=\"text-align: justify;\">El tipo CV est\u00e1 disponible en versi\u00f3n EX certificada para uso en \u00e1reas peligrosas hasta 200 \u00b0 C.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/velocimetros\/\">VELOC\u00cdMETROS | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\"><strong>Sensores de presi\u00f3n din\u00e1mica para monitorizaci\u00f3n de la combusti\u00f3n<\/strong><\/h3>\n<p style=\"text-align: justify;\">La <strong>serie CP<\/strong> de sensores piezoel\u00e9ctricos de presi\u00f3n din\u00e1mica son de alta temperatura, dise\u00f1ados para mediciones de larga duraci\u00f3n y monitorizaci\u00f3n de la combusti\u00f3n, pulsaciones de la c\u00e1mara de combusti\u00f3n y din\u00e1mica de combusti\u00f3n en turbinas de gas. Se requiere un acondicionador de se\u00f1al IPC externo para convertir la carga de bajo nivel se\u00f1al (pC \/ g) emitida por un sensor CP en una se\u00f1al de corriente o tensi\u00f3n adecuada para transmisi\u00f3n al sistema de monitorizaci\u00f3n. Esta separaci\u00f3n de la electr\u00f3nica permite alto rendimiento del sensor a temperaturas m\u00e1s altas.<\/p>\n<p style=\"text-align: justify;\">Los sensores CP utilizan dise\u00f1os patentados compensados por aceleraci\u00f3n para permitir las m\u00e1s altas temperaturas y sensibilidades a la presi\u00f3n en la industria<\/p>\n<p style=\"text-align: justify;\">Disponible en versiones Ex certificadas internacionalmente para uso en \u00e1reas peligrosas. Adecuado para entornos de alta temperatura (hasta 700 \u00b0 C) y aplicaciones relacionadas con la seguridad en cadenas de medida SIL 2.<\/p>\n<p style=\"text-align: justify;\">Permite \/ admite el monitoreo de combusti\u00f3n pobre a alta temperatura: la clave para reducir las emisiones de \u00a0NOx y de otros gases.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/sensores-de-presion-dinamica\/\">Sensores de Presi\u00f3n Din\u00e1mica | TSI. T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<h3 style=\"text-align: justify;\"><strong>Sensores de Proximidad para vibraci\u00f3n relativa y otras medidas<\/strong><\/h3>\n<p style=\"text-align: justify;\">La serie TQ de sensores de proximidad son sensores resistentes que utilizan el principio de corrientes par\u00e1sitas para permitir la medici\u00f3n sin contacto de vibraci\u00f3n relativa, posici\u00f3n y otros mediciones en entornos hostiles. Permiten mediciones de vibraci\u00f3n radial, posici\u00f3n axial, velocidad de rotaci\u00f3n\u00a0 y referencia de fase (1\/Rev Pulse).<\/p>\n<p style=\"text-align: justify;\">Una cadena de medici\u00f3n basada en TQ consta de un sensor de proximidad, una extensi\u00f3n opcional de cable y un acondicionador de se\u00f1al IQS, configurado para la aplicaci\u00f3n particular.<\/p>\n<p style=\"text-align: justify;\">Se requiere que el acondicionador de se\u00f1al realice todo el procesamiento de se\u00f1al requerido y proporcione una se\u00f1al de corriente o voltaje adecuada para su transmisi\u00f3n al sistema de monitorizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Las cadenas de medici\u00f3n basadas en TQ son ideales para la medici\u00f3n y control de la vibraci\u00f3n relativa y la posici\u00f3n axial de los ejes de las m\u00e1quinas giratorias, como los que se encuentran en las turbinas de vapor, gas e hidr\u00e1ulicas, as\u00ed como en los generadores, turbocompresores y bombas. Tambi\u00e9n pueden medir la velocidad de rotaci\u00f3n y \/ o proporcionar se\u00f1ales de referencia de fase (pulso 1 \/ REV). Disponible en versiones est\u00e1ndar y en versiones Ex certificadas internacionalmente para uso en \u00e1reas peligrosas.<\/p>\n<p style=\"text-align: justify;\">Amplia familia de sensores con diferentes rangos de medici\u00f3n (sensibilidades), opciones de montaje (est\u00e1ndar o inverso) y capacidades de presi\u00f3n (hasta 100 bar). Adecuado para aplicaciones relacionadas con la seguridad que utilizan cadenas de medici\u00f3n SIL 2 y cumple con API 670 5ta edici\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/vibracion-relativa\/\">Vibraci\u00f3n relativa | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/DS_TQ902_TQ912_EA902_IQS900-en.pdf\">TQ902\/TQ912, EA902 and IQS900 proximity measurement chain data sheet (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\"><strong>Sistema de monitorizaci\u00f3n de Air Gap<\/strong><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Tecnolog\u00eda de campo el\u00e9ctrico (capacitancia) para la medici\u00f3n sin contacto del entrehierro en generadores hidroel\u00e9ctricos, y otros grandes alternadores y motores.<\/li>\n<li>Los sistemas de medici\u00f3n de air gap LS12x \/ ILS73x proporcionan tres se\u00f1ales de salida de voltaje (perfil de polo, perfil de rotor y espacio m\u00ednimo(gap)) y una se\u00f1al de salida de corriente (polo perfil, perfil del rotor o espacio m\u00ednimo(gap)) para la transmisi\u00f3n de la se\u00f1al a distancias m\u00e1s largas.<\/li>\n<li>El espacio m\u00ednimo (gap) proporciona el valor m\u00ednimo del air gap para todos los polos del rotor: sin ning\u00fan postprocesamiento, y normalmente est\u00e1 conectado directamente a un sistema de monitorizaci\u00f3n.<\/li>\n<li>Instalaci\u00f3n f\u00e1cil y r\u00e1pida con filtrado mejorado de ruido y picos (inducida por altas corrientes de excitaci\u00f3n).<\/li>\n<li>Se\u00f1al de air gap para protecci\u00f3n directa. Resultados precisos en todos los rangos de temperatura y medici\u00f3n<\/li>\n<li>Alojamiento de sondas de expansi\u00f3n<\/li>\n<li>Tecnolog\u00eda de corrientes par\u00e1sitas para la medici\u00f3n sin contacto de la expansi\u00f3n absoluta de la carcasa en m\u00e1quinas t\u00e9rmicas medianas a grandes, como turbinas de gas y vapor.<\/li>\n<li>Electr\u00f3nica integrada con se\u00f1al de salida de 4-20 mA. Grado de protecci\u00f3n IP54 (a prueba de salpicaduras).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/air-gap\/\">Air Gap | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\"><strong>Sensores de Vibraci\u00f3n de prop\u00f3sito general<\/strong><\/h3>\n<p style=\"text-align: justify;\">El CE6xx, CVS100 y PV6xx son de uso general. Sensores de vibraci\u00f3n piezoel\u00e9ctricos dise\u00f1ados para optimizar la medici\u00f3n y seguimiento de vibraciones de planta (BOP), en equipos tales como compresores, cajas de cambios, motores, bombas y ventiladores, as\u00ed como maquinaria m\u00e1s grande como turbinas hidr\u00e1ulicas.<\/p>\n<p style=\"text-align: justify;\">El CE620 y CE687 son aceler\u00f3metros piezoel\u00e9ctricos que proporcionan voltaje (IEPE) y salidas de corriente (4 a 20 mA) respectivamente, mientras que PV660 y PV685 son sensores de velocidad piezoel\u00e9ctricos que tambi\u00e9n proporcionan salidas de voltaje y corriente respectivamente.<\/p>\n<p style=\"text-align: justify;\">La serie CVS100 de interruptores de vibraci\u00f3n permite un control de vibraciones rentable para m\u00e1quinas independientes y equipos BOP, como ventiladores, bombas, centrifugadoras, molinos, engranajes, etc., de cuyo funcionamiento dependen importantes instalaciones o procesos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/acelerometros\/\">Aceler\u00f3metros: Sensores VIBRO-METER | TSI. T\u00e9cnicas y Servicios (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/velocimetros\/\">VELOC\u00cdMETROS | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3 style=\"text-align: justify;\"><strong>Sondas de proximidad de prop\u00f3sito general<\/strong><\/h3>\n<ul style=\"text-align: justify;\">\n<li>Las series WW y RE de transductores de proximidad se utilizan en combinaci\u00f3n con transmisor o convertidor para medici\u00f3n directa de corriente 4-20 mA, vibraci\u00f3n del eje o el desplazamiento relativo.<\/li>\n<li>Las mediciones se realizan seg\u00fan el principio de las corrientes par\u00e1sitas.<\/li>\n<li>El transductor de proximidad WW se utiliza en combinaci\u00f3n con el transmisor TWW101 M1 para mediciones sin contacto de desplazamientos.<\/li>\n<li>Los transductores de proximidad RE022, RE030 miden con la ayuda de el transmisor RE101 \/ R102 sin contacto con la posici\u00f3n relativa de un objeto.<\/li>\n<li>El amplio rango de medici\u00f3n lo hace ideal para monitorizaci\u00f3n de turbinas de vapor.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/uncategorised\/ww007\/\">WW007 &#8211; Vibro-meter Catalogue (meggittsensing.com)<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/DS_TSW201-de-en.pdf\">TSW201 Transmitter Datenblatt \/ transmitter data sheet (meggittsensing.com)<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31836,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento.\r\n\r\nMeggitt SA es reconocida por sus m\u00e1s altos est\u00e1ndares de calidad, disponiendo de certificaciones regulares desde la primera certificaci\u00f3n ISO 9000 all\u00e1 por 1995. Los certificados de gesti\u00f3n ambiental fueron otorgados por AFNOR Certification. Adem\u00e1s, para ciertos productos espec\u00edficos dispone de <strong>certificaci\u00f3n Ex<\/strong> que permite puedan usarse en \u00e1reas peligrosas (atm\u00f3sferas potencialmente explosivas), por ejemplo, instaladas en turbinas de gas. Algunos tienen <strong>certificaci\u00f3n de seguridad SIL<\/strong> para que puedan utilizarse en aplicaciones relacionadas con la seguridad (contextos de seguridad funcional), por ejemplo, sistemas de protecci\u00f3n cr\u00edtica.\r\n\r\nLa amplia gama de sensores y cadenas de medida (Vibraci\u00f3n Absoluta, Presi\u00f3n Din\u00e1mica, Air Gap, y velocidad y vibraci\u00f3n relativa) se pueden utilizar con nuestro sistema de monitorizaci\u00f3n (VM 600 y\/o Vibrosmart) junto con el software Vibrosight (o de terceros sistemas) con el fin de proporcionar soluciones completas para la vigilancia y protecci\u00f3n de maquinaria y procesos cr\u00edticos. Desde ambientes est\u00e1ndar ambientes a condiciones extremas.<img class=\"aligncenter wp-image-35940\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2022\/03\/FOTO-1-1-1024x522.jpg\" alt=\"\" width=\"840\" height=\"429\" \/>\r\n\r\n<img class=\"aligncenter wp-image-35942\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2022\/03\/FOTO-2-1024x514.jpg\" alt=\"\" width=\"910\" height=\"457\" \/>\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sistemas-de-monitorizacion-y-proteccion\/sistema-vm600\/\">Sistema VM600 | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\nEl portoflio de Vibrometer esta especializado en productos y soluciones para la protecci\u00f3n de maquinaria y monitorizaci\u00f3n de maquinaria rotativa cr\u00edtica como pueden ser Hidroturbinas, Turbinas de gas y vapor... La <strong>serie CA<\/strong> de sensores de vibraci\u00f3n son de alta temperatura (hasta 700\u00baC), aceler\u00f3metros piezoel\u00e9ctricos dise\u00f1ados para realizar mediciones de largos per\u00edodos y seguimiento de la vibraci\u00f3n absoluta en la mayor\u00eda de ambientes con condiciones severas de medida.\r\n\r\nSe requiere un acondicionador de se\u00f1al IPC externo para convertir la carga de bajo nivel, se\u00f1al (pC \/ g) emitida por un sensor CA en una se\u00f1al de corriente o voltaje adecuada para transmisi\u00f3n al sistema de monitorizaci\u00f3n. Esta separaci\u00f3n de la electr\u00f3nica permite un alto rendimiento del sensor a temperaturas m\u00e1s altas. Cabe destacar que son equipos adecuados para su uso en aplicaciones relacionados con la seguridad, que utilizan cadenas de medida SIL 2.\r\n\r\n<a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/sensors-and-signal-conditioners\/high-temperature-vibration-sensors\/ca202-piezoelectric-accelerometer\/\">CA202 piezoelectric accelerometer - Vibro-meter Catalogue (meggittsensing.com)<\/a>\r\n\r\n<a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/IPC707_product_overview-en.pdf\">IPC707 signal conditioner product overview (meggittsensing.com)<\/a>\r\n\r\n<a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/sensors-and-signal-conditioners\/other\/gsi127-galvanic-separation-unit\/\">GSI127 galvanic separation unit - Vibro-meter Catalogue (meggittsensing.com)<\/a>\r\n\r\n&nbsp;\r\n\r\nLos sensores de vibraci\u00f3n con electr\u00f3nica integrada se usan en aplicaciones que no requieren las capacidades para altas temperaturas de la serie CA.\r\n\r\nLa <strong>serie CE<\/strong> de sensores son aceler\u00f3metros piezoel\u00e9ctricos que vienen con componentes electr\u00f3nicos integrados para aplicaciones de temperaturas m\u00e1s altas o electr\u00f3nica integrada para aplicaciones de baja temperatura, sin necesidad de acondicionadores de se\u00f1al y cableado m\u00e1s sencillo, en versiones est\u00e1ndar y Ex certificadas. Estos sensores son adecuados para la medici\u00f3n y monitorizaci\u00f3n de vibraciones en entornos hostiles, como turbinas de gas o vapor, compresores, bombas y ventiladores.\r\n\r\nEl <strong>SE120<\/strong> es un aceler\u00f3metro piezorresistivo de alta sensibilidad adecuado para medici\u00f3n y monitorizaci\u00f3n de vibraciones a frecuencias m\u00e1s bajas en condiciones extremas, como turbinas hidr\u00e1ulicas y ventiladores.\r\n\r\n<a href=\"https:\/\/catalogue.meggittsensing.com\/wp-content\/uploads\/2021\/03\/datasheets_DS_SE120-en.pdf\">DS_SE120-en.fm (meggittsensing.com)<\/a>\r\n\r\n&nbsp;\r\n\r\nLos sensores de vibraciones con salida de velocidad se pueden usar para el control de vibraciones de maquinaria rotativa de baja velocidad, midiendo vibraciones absolutas a baja frecuencia, en turbinas hidr\u00e1ulicas o en aplicaciones de ventiladores. El sensor de velocidad dise\u00f1ado de acuerdo con el principio de bobina m\u00f3vil proporciona una alta relaci\u00f3n se\u00f1al \/ ruido en el rango de baja frecuencia.\r\n\r\nEl tipo CV est\u00e1 disponible en versi\u00f3n EX certificada para uso en \u00e1reas peligrosas hasta 200 \u00b0 C.\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/velocimetros\/\">VELOC\u00cdMETROS | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\n&nbsp;\r\n<h3><strong>Sensores de presi\u00f3n din\u00e1mica para monitorizaci\u00f3n de la combusti\u00f3n<\/strong><\/h3>\r\nLa <strong>serie CP<\/strong> de sensores piezoel\u00e9ctricos de presi\u00f3n din\u00e1mica son de alta temperatura, dise\u00f1ados para mediciones de larga duraci\u00f3n y monitorizaci\u00f3n de la combusti\u00f3n, pulsaciones de la c\u00e1mara de combusti\u00f3n y din\u00e1mica de combusti\u00f3n en turbinas de gas. Se requiere un acondicionador de se\u00f1al IPC externo para convertir la carga de bajo nivel se\u00f1al (pC \/ g) emitida por un sensor CP en una se\u00f1al de corriente o tensi\u00f3n adecuada para transmisi\u00f3n al sistema de monitorizaci\u00f3n. Esta separaci\u00f3n de la electr\u00f3nica permite alto rendimiento del sensor a temperaturas m\u00e1s altas.\r\n\r\nLos sensores CP utilizan dise\u00f1os patentados compensados por aceleraci\u00f3n para permitir las m\u00e1s altas temperaturas y sensibilidades a la presi\u00f3n en la industria\r\n\r\nDisponible en versiones Ex certificadas internacionalmente para uso en \u00e1reas peligrosas. Adecuado para entornos de alta temperatura (hasta 700 \u00b0 C) y aplicaciones relacionadas con la seguridad en cadenas de medida SIL 2.\r\n\r\nPermite \/ admite el monitoreo de combusti\u00f3n pobre a alta temperatura: la clave para reducir las emisiones de \u00a0NOx y de otros gases.\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/sensores-de-presion-dinamica\/\">Sensores de Presi\u00f3n Din\u00e1mica | TSI. T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\n<strong>\u00a0<\/strong>\r\n<h3><strong>Sensores de Proximidad para vibraci\u00f3n relativa y otras medidas<\/strong><\/h3>\r\nLa serie TQ de sensores de proximidad son sensores resistentes que utilizan el principio de corrientes par\u00e1sitas para permitir la medici\u00f3n sin contacto de vibraci\u00f3n relativa, posici\u00f3n y otros mediciones en entornos hostiles. Permiten mediciones de vibraci\u00f3n radial, posici\u00f3n axial, velocidad de rotaci\u00f3n\u00a0 y referencia de fase (1\/Rev Pulse).\r\n\r\nUna cadena de medici\u00f3n basada en TQ consta de un sensor de proximidad, una extensi\u00f3n opcional de cable y un acondicionador de se\u00f1al IQS, configurado para la aplicaci\u00f3n particular.\r\n\r\nSe requiere que el acondicionador de se\u00f1al realice todo el procesamiento de se\u00f1al requerido y proporcione una se\u00f1al de corriente o voltaje adecuada para su transmisi\u00f3n al sistema de monitorizaci\u00f3n.\r\n\r\nLas cadenas de medici\u00f3n basadas en TQ son ideales para la medici\u00f3n y control de la vibraci\u00f3n relativa y la posici\u00f3n axial de los ejes de las m\u00e1quinas giratorias, como los que se encuentran en las turbinas de vapor, gas e hidr\u00e1ulicas, as\u00ed como en los generadores, turbocompresores y bombas. Tambi\u00e9n pueden medir la velocidad de rotaci\u00f3n y \/ o proporcionar se\u00f1ales de referencia de fase (pulso 1 \/ REV). Disponible en versiones est\u00e1ndar y en versiones Ex certificadas internacionalmente para uso en \u00e1reas peligrosas.\r\n\r\nAmplia familia de sensores con diferentes rangos de medici\u00f3n (sensibilidades), opciones de montaje (est\u00e1ndar o inverso) y capacidades de presi\u00f3n (hasta 100 bar). Adecuado para aplicaciones relacionadas con la seguridad que utilizan cadenas de medici\u00f3n SIL 2 y cumple con API 670 5ta edici\u00f3n.\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/vibracion-relativa\/\">Vibraci\u00f3n relativa | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\n<a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/DS_TQ902_TQ912_EA902_IQS900-en.pdf\">TQ902\/TQ912, EA902 and IQS900 proximity measurement chain data sheet (meggittsensing.com)<\/a>\r\n\r\n&nbsp;\r\n<h3><strong>Sistema de monitorizaci\u00f3n de Air Gap<\/strong><\/h3>\r\n<ul>\r\n \t<li>Tecnolog\u00eda de campo el\u00e9ctrico (capacitancia) para la medici\u00f3n sin contacto del entrehierro en generadores hidroel\u00e9ctricos, y otros grandes alternadores y motores.<\/li>\r\n \t<li>Los sistemas de medici\u00f3n de air gap LS12x \/ ILS73x proporcionan tres se\u00f1ales de salida de voltaje (perfil de polo, perfil de rotor y espacio m\u00ednimo(gap)) y una se\u00f1al de salida de corriente (polo perfil, perfil del rotor o espacio m\u00ednimo(gap)) para la transmisi\u00f3n de la se\u00f1al a distancias m\u00e1s largas.<\/li>\r\n \t<li>El espacio m\u00ednimo (gap) proporciona el valor m\u00ednimo del air gap para todos los polos del rotor: sin ning\u00fan postprocesamiento, y normalmente est\u00e1 conectado directamente a un sistema de monitorizaci\u00f3n.<\/li>\r\n \t<li>Instalaci\u00f3n f\u00e1cil y r\u00e1pida con filtrado mejorado de ruido y picos (inducida por altas corrientes de excitaci\u00f3n).<\/li>\r\n \t<li>Se\u00f1al de air gap para protecci\u00f3n directa. Resultados precisos en todos los rangos de temperatura y medici\u00f3n<\/li>\r\n \t<li>Alojamiento de sondas de expansi\u00f3n<\/li>\r\n \t<li>Tecnolog\u00eda de corrientes par\u00e1sitas para la medici\u00f3n sin contacto de la expansi\u00f3n absoluta de la carcasa en m\u00e1quinas t\u00e9rmicas medianas a grandes, como turbinas de gas y vapor.<\/li>\r\n \t<li>Electr\u00f3nica integrada con se\u00f1al de salida de 4-20 mA. Grado de protecci\u00f3n IP54 (a prueba de salpicaduras).<\/li>\r\n<\/ul>\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/air-gap\/\">Air Gap | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\n&nbsp;\r\n<h3><strong>Sensores de Vibraci\u00f3n de prop\u00f3sito general<\/strong><\/h3>\r\nEl CE6xx, CVS100 y PV6xx son de uso general. Sensores de vibraci\u00f3n piezoel\u00e9ctricos dise\u00f1ados para optimizar la medici\u00f3n y seguimiento de vibraciones de planta (BOP), en equipos tales como compresores, cajas de cambios, motores, bombas y ventiladores, as\u00ed como maquinaria m\u00e1s grande como turbinas hidr\u00e1ulicas.\r\n\r\nEl CE620 y CE687 son aceler\u00f3metros piezoel\u00e9ctricos que proporcionan voltaje (IEPE) y salidas de corriente (4 a 20 mA) respectivamente, mientras que PV660 y PV685 son sensores de velocidad piezoel\u00e9ctricos que tambi\u00e9n proporcionan salidas de voltaje y corriente respectivamente.\r\n\r\nLa serie CVS100 de interruptores de vibraci\u00f3n permite un control de vibraciones rentable para m\u00e1quinas independientes y equipos BOP, como ventiladores, bombas, centrifugadoras, molinos, engranajes, etc., de cuyo funcionamiento dependen importantes instalaciones o procesos.\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/acelerometros\/\">Aceler\u00f3metros: Sensores VIBRO-METER | TSI. T\u00e9cnicas y Servicios (tsisl.es)<\/a>\r\n\r\n<a href=\"https:\/\/tsisl.es\/instrumentacion\/vibro-meter\/sensores\/velocimetros\/\">VELOC\u00cdMETROS | T\u00e9cnicas y Servicios de Ingenier\u00eda (tsisl.es)<\/a>\r\n\r\n&nbsp;\r\n<h3><strong>Sondas de proximidad de prop\u00f3sito general<\/strong><\/h3>\r\n<ul>\r\n \t<li>Las series WW y RE de transductores de proximidad se utilizan en combinaci\u00f3n con transmisor o convertidor para medici\u00f3n directa de corriente 4-20 mA, vibraci\u00f3n del eje o el desplazamiento relativo.<\/li>\r\n \t<li>Las mediciones se realizan seg\u00fan el principio de las corrientes par\u00e1sitas.<\/li>\r\n \t<li>El transductor de proximidad WW se utiliza en combinaci\u00f3n con el transmisor TWW101 M1 para mediciones sin contacto de desplazamientos.<\/li>\r\n \t<li>Los transductores de proximidad RE022, RE030 miden con la ayuda de el transmisor RE101 \/ R102 sin contacto con la posici\u00f3n relativa de un objeto.<\/li>\r\n \t<li>El amplio rango de medici\u00f3n lo hace ideal para monitorizaci\u00f3n de turbinas de vapor.<\/li>\r\n<\/ul>\r\n<a href=\"https:\/\/catalogue.meggittsensing.com\/shop\/uncategorised\/ww007\/\">WW007 - Vibro-meter Catalogue (meggittsensing.com)<\/a>\r\n\r\n<a href=\"https:\/\/meggittsensing.com\/wp-content\/uploads\/DS_TSW201-de-en.pdf\">TSW201 Transmitter Datenblatt \/ transmitter data sheet (meggittsensing.com)<\/a>","_et_gb_content_width":"","footnotes":""},"categories":[22,16,20],"tags":[150,155,36,156],"class_list":["post-35939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sensores","category-sistemas-de-monitorizacion-en-continuo","category-sistemas-de-supervision-analisis-y-diagnostico","tag-instrumentacion","tag-meggitt","tag-tsisl","tag-vibrometer"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"TSI_Admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"T\u00e9cnicas y Servicios de Ingenier\u00eda - Servicios de ingenier\u00eda de ruido y vibraciones.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-26T07:59:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-04-11T09:18:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@tsisl_oficial\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@tsisl_oficial\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#blogposting\",\"name\":\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\\u00edtica - T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"headline\":\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\\u00edtica\",\"author\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/adm_ireneb\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tsisl.es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-instrumentacion-ingenieria-naval-TSI-meggitt-vibrometer.jpg\",\"width\":500,\"height\":250},\"datePublished\":\"2021-08-26T09:59:41+02:00\",\"dateModified\":\"2022-04-11T11:18:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#webpage\"},\"articleSection\":\"Sensores, Sistemas de Monitorizaci\\u00f3n en Continuo, Sistemas de Supervisi\\u00f3n, An\\u00e1lisis y Diagn\\u00f3stico, INSTRUMENTACI\\u00d3N, Meggitt, tsisl, Vibrometer, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/sistemas-de-monitorizacion-en-continuo\\\/#listItem\",\"name\":\"Sistemas de Monitorizaci\\u00f3n en Continuo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/sistemas-de-monitorizacion-en-continuo\\\/#listItem\",\"position\":2,\"name\":\"Sistemas de Monitorizaci\\u00f3n en Continuo\",\"item\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/sistemas-de-monitorizacion-en-continuo\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#listItem\",\"name\":\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\\u00edtica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#listItem\",\"position\":3,\"name\":\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\\u00edtica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/sistemas-de-monitorizacion-en-continuo\\\/#listItem\",\"name\":\"Sistemas de Monitorizaci\\u00f3n en Continuo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\",\"name\":\"T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Servicios de ingenier\\u00eda de ruido y vibraciones.\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/tsisl_oficial\",\"https:\\\/\\\/www.youtube.com\\\/@tsisl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2298820\\\/admin\\\/feed\\\/posts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/adm_ireneb\\\/#author\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/adm_ireneb\\\/\",\"name\":\"TSI_Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/381f974315af33b5885ca550ea40e0f1af9cae72d743ad0ae6a11a78bbcb92d6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"TSI_Admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#webpage\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/\",\"name\":\"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\\u00edtica - T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Durante 70 a\\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\\u00f3n y monitorizaci\\u00f3n de vibraciones, presi\\u00f3n y air-gap en plantas y equipos cr\\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\\u00e1s altos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/adm_ireneb\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/adm_ireneb\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tsisl.es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-instrumentacion-ingenieria-naval-TSI-meggitt-vibrometer.jpg\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#mainImage\",\"width\":500,\"height\":250},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2021\\\/08\\\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\\\/#mainImage\"},\"datePublished\":\"2021-08-26T09:59:41+02:00\",\"dateModified\":\"2022-04-11T11:18:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"name\":\"T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Servicios de ingenier\\u00eda de ruido y vibraciones.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos","canonical_url":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#blogposting","name":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda","headline":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica","author":{"@id":"https:\/\/tsisl.es\/es\/author\/adm_ireneb\/#author"},"publisher":{"@id":"https:\/\/tsisl.es\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/logo-instrumentacion-ingenieria-naval-TSI-meggitt-vibrometer.jpg","width":500,"height":250},"datePublished":"2021-08-26T09:59:41+02:00","dateModified":"2022-04-11T11:18:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#webpage"},"isPartOf":{"@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#webpage"},"articleSection":"Sensores, Sistemas de Monitorizaci\u00f3n en Continuo, Sistemas de Supervisi\u00f3n, An\u00e1lisis y Diagn\u00f3stico, INSTRUMENTACI\u00d3N, Meggitt, tsisl, Vibrometer, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/tsisl.es\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/#listItem","name":"Sistemas de Monitorizaci\u00f3n en Continuo"}},{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/#listItem","position":2,"name":"Sistemas de Monitorizaci\u00f3n en Continuo","item":"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#listItem","name":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#listItem","position":3,"name":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica","previousItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/#listItem","name":"Sistemas de Monitorizaci\u00f3n en Continuo"}}]},{"@type":"Organization","@id":"https:\/\/tsisl.es\/es\/#organization","name":"T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Servicios de ingenier\u00eda de ruido y vibraciones.","url":"https:\/\/tsisl.es\/es\/","sameAs":["https:\/\/twitter.com\/tsisl_oficial","https:\/\/www.youtube.com\/@tsisl","https:\/\/www.linkedin.com\/company\/2298820\/admin\/feed\/posts\/"]},{"@type":"Person","@id":"https:\/\/tsisl.es\/es\/author\/adm_ireneb\/#author","url":"https:\/\/tsisl.es\/es\/author\/adm_ireneb\/","name":"TSI_Admin","image":{"@type":"ImageObject","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/381f974315af33b5885ca550ea40e0f1af9cae72d743ad0ae6a11a78bbcb92d6?s=96&d=mm&r=g","width":96,"height":96,"caption":"TSI_Admin"}},{"@type":"WebPage","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#webpage","url":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/","name":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/tsisl.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#breadcrumblist"},"author":{"@id":"https:\/\/tsisl.es\/es\/author\/adm_ireneb\/#author"},"creator":{"@id":"https:\/\/tsisl.es\/es\/author\/adm_ireneb\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/logo-instrumentacion-ingenieria-naval-TSI-meggitt-vibrometer.jpg","@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#mainImage","width":500,"height":250},"primaryImageOfPage":{"@id":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/#mainImage"},"datePublished":"2021-08-26T09:59:41+02:00","dateModified":"2022-04-11T11:18:10+02:00"},{"@type":"WebSite","@id":"https:\/\/tsisl.es\/es\/#website","url":"https:\/\/tsisl.es\/es\/","name":"T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Servicios de ingenier\u00eda de ruido y vibraciones.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/tsisl.es\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"T\u00e9cnicas y Servicios de Ingenier\u00eda - Servicios de ingenier\u00eda de ruido y vibraciones.","og:type":"article","og:title":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda","og:description":"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos","og:url":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/","og:image":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg","og:image:secure_url":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg","og:image:width":500,"og:image:height":500,"article:published_time":"2021-08-26T07:59:41+00:00","article:modified_time":"2022-04-11T09:18:10+00:00","twitter:card":"summary","twitter:site":"@tsisl_oficial","twitter:title":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica - T\u00e9cnicas y Servicios de Ingenier\u00eda","twitter:description":"Durante 70 a\u00f1os, los productos y la experiencia de Meggitt Vibrometer han permitido el desarrollo de soluciones de alto nivel para la detecci\u00f3n y monitorizaci\u00f3n de vibraciones, presi\u00f3n y air-gap en plantas y equipos cr\u00edticos, para alcanzar altos niveles de confiabilidad, disponibilidad de la m\u00e1quina y rendimiento. Meggitt SA es reconocida por sus m\u00e1s altos","twitter:creator":"@tsisl_oficial","twitter:image":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg"},"aioseo_meta_data":{"post_id":"35939","title":"#post_title #separator_sa #site_title","description":"#post_excerpt","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":"#post_title #separator_sa #site_title","og_description":"#post_excerpt","og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-22 09:13:41","updated":"2025-06-05 10:58:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tsisl.es\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/\" title=\"Sistemas de Monitorizaci\u00f3n en Continuo\">Sistemas de Monitorizaci\u00f3n en Continuo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/tsisl.es\/es\/"},{"label":"Sistemas de Monitorizaci\u00f3n en Continuo","link":"https:\/\/tsisl.es\/es\/category\/sistemas-de-monitorizacion-en-continuo\/"},{"label":"Sensores y cadena de medida para turbomaquinaria y maquinaria rotativa cr\u00edtica","link":"https:\/\/tsisl.es\/es\/2021\/08\/sensores-y-cadena-de-medida-para-turbomaquinaria-y-maquinaria-rotativa-critica\/"}],"_links":{"self":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/35939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/comments?post=35939"}],"version-history":[{"count":6,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/35939\/revisions"}],"predecessor-version":[{"id":36370,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/35939\/revisions\/36370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/media\/31836"}],"wp:attachment":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/media?parent=35939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/categories?post=35939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/tags?post=35939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}