{"id":122,"date":"2013-04-02T14:23:48","date_gmt":"2013-04-02T14:23:48","guid":{"rendered":"https:\/\/tsisl.magicalwebstudio.com\/index.php\/2013\/04\/02\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/"},"modified":"2022-04-11T13:45:31","modified_gmt":"2022-04-11T11:45:31","slug":"la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion","status":"publish","type":"post","link":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/","title":{"rendered":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n."},"content":{"rendered":"<p style=\"text-align: justify;\">Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el <em>\u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d<\/em>, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE ALMARAZ (CNA).<\/p>\n<p style=\"text-align: justify;\">Este curso especializado est\u00e1 enmarcado dentro del Programa de Mejora Continua que C. N. ALMARAZ viene desarrollando desde hace m\u00e1s de quince a\u00f1os en las diferentes \u00e1reas y procesos y dirigido fundamentalmente a la mejora de la Seguridad y Disponibilidad de la planta.<\/p>\n<p style=\"text-align: justify;\">En los apartados espec\u00edficos de Circuito Primario y Equipos Rotativos esenciales: Turbogrupo, Tubobombas, Bombas de Refrigeraci\u00f3n, etc; las <a href=\"https:\/\/tsisl.es\/25\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10162 alignleft\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/cna1-3-300x164.jpg\" alt=\"curso certificacion analista de vibraciones\" width=\"300\" height=\"164\" \/><\/a>actuaciones se han dirigido a la total renovaci\u00f3n y modernizaci\u00f3n de los Sistemas de Monitorizaci\u00f3n y Vigilancia en Continuo de todos y cada uno de estos equipos y sistemas.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, y para el resto de las unidades de la planta, y dentro del Marco Regulatorio establecido por ASME, las actuaciones se han dirigido a la aplicaci\u00f3n de un Eficiente Mantenimiento Predictivo de Aver\u00edas (MPA) o Mantenimiento Basado en Condici\u00f3n (CBM), que permite adem\u00e1s de garantizar el estricto cumplimiento con los Criterios del C\u00f3digo ASME, complementariamente, aumentar la disponibilidad de estos equipos minimizando el n\u00famero de paradas imprevistas y reducir\u00a0 sus costes de mantenimiento.<\/p>\n<p style=\"text-align: justify;\">La eficacia de la aplicaci\u00f3n de esta mejora en C.N. ALMARAZ, puede concretarse en el hecho de que, actualmente, todos los equipos cumplen satisfactoriamente con el C\u00f3digo ASME, en lo relativo a vibraciones; y qu\u00e9 en los \u00faltimos a\u00f1os\u00a0 el n\u00famero de indisponibilidades en todos los equipos, esenciales y convencionales, se ha reducido a m\u00ednimos. En todo este proceso, C.N. ALMARAZ ha posicionado la Formaci\u00f3n y Especializaci\u00f3n del personal dedicado como piedra angular del mismo; tarea para la que ha confiado en la especializaci\u00f3n de TSI.<\/p>\n<p style=\"text-align: justify;\">El presente Curso de Especializaci\u00f3n, tras un repaso de los conceptos b\u00e1sicos, se ha centrado en profundizar en el manejo y funcionalidades de los diferentes equipos y sistemas de medida, an\u00e1lisis y control de vibraciones y otros par\u00e1metros, instalados en planta. Finalmente, como complemento y de forma muy espec\u00edfica, se han dedicado sesiones monogr\u00e1ficas al repaso de Hist\u00f3ricos de Aver\u00edas acaecidas en algunos equipos con anterioridad a la implantaci\u00f3n de Programa de Mejora. En base a toda esta actividad, se ha puesto en marcha, y para unidades espec\u00edficas, un Plan de Modificaciones de Dise\u00f1o dirigido a mejorar aquellas unidades que, desde la puesta en marcha, aparec\u00edan como \u201ccriticas\u201d.<\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p style=\"text-align: justify;\">Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el <em>\u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d<\/em>, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE ALMARAZ (CNA).<\/p> <p style=\"text-align: justify;\">Este curso especializado est\u00e1 enmarcado dentro del Programa de Mejora Continua que C. N. ALMARAZ viene desarrollando desde hace m\u00e1s de quince a\u00f1os en las diferentes \u00e1reas y procesos y dirigido fundamentalmente a la mejora de la Seguridad y Disponibilidad de la planta.<\/p> <p style=\"text-align: justify;\">En los apartados espec\u00edficos de Circuito Primario y Equipos Rotativos esenciales: Turbogrupo, Tubobombas, Bombas de Refrigeraci\u00f3n, etc; las <a href=\"https:\/\/tsisl.es\/25\"><img class=\"size-medium wp-image-10162 alignleft\" src=\"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/cna1-3-300x164.jpg\" alt=\"curso certificacion analista de vibraciones\" width=\"300\" height=\"164\" \/><\/a>actuaciones se han dirigido a la total renovaci\u00f3n y modernizaci\u00f3n de los Sistemas de Monitorizaci\u00f3n y Vigilancia en Continuo de todos y cada uno de estos equipos y sistemas.<\/p> <p style=\"text-align: justify;\">Por otro lado, y para el resto de las unidades de la planta, y dentro del Marco Regulatorio establecido por ASME, las actuaciones se han dirigido a la aplicaci\u00f3n de un Eficiente Mantenimiento Predictivo de Aver\u00edas (MPA) o Mantenimiento Basado en Condici\u00f3n (CBM), que permite adem\u00e1s de garantizar el estricto cumplimiento con los Criterios del C\u00f3digo ASME, complementariamente, aumentar la disponibilidad de estos equipos minimizando el n\u00famero de paradas imprevistas y reducir\u00a0 sus costes de mantenimiento.<\/p> <p style=\"text-align: justify;\">La eficacia de la aplicaci\u00f3n de esta mejora en C.N. ALMARAZ, puede concretarse en el hecho de que, actualmente, todos los equipos cumplen satisfactoriamente con el C\u00f3digo ASME, en lo relativo a vibraciones; y qu\u00e9 en los \u00faltimos a\u00f1os\u00a0 el n\u00famero de indisponibilidades en todos los equipos, esenciales y convencionales, se ha reducido a m\u00ednimos. En todo este proceso, C.N. ALMARAZ ha posicionado la Formaci\u00f3n y Especializaci\u00f3n del personal dedicado como piedra angular del mismo; tarea para la que ha confiado en la especializaci\u00f3n de TSI.<\/p> <p style=\"text-align: justify;\">El presente Curso de Especializaci\u00f3n, tras un repaso de los conceptos b\u00e1sicos, se ha centrado en profundizar en el manejo y funcionalidades de los diferentes equipos y sistemas de medida, an\u00e1lisis y control de vibraciones y otros par\u00e1metros, instalados en planta. Finalmente, como complemento y de forma muy espec\u00edfica, se han dedicado sesiones monogr\u00e1ficas al repaso de Hist\u00f3ricos de Aver\u00edas acaecidas en algunos equipos con anterioridad a la implantaci\u00f3n de Programa de Mejora. En base a toda esta actividad, se ha puesto en marcha, y para unidades espec\u00edficas, un Plan de Modificaciones de Dise\u00f1o dirigido a mejorar aquellas unidades que, desde la puesta en marcha, aparec\u00edan como \u201ccriticas\u201d.<\/p>","_et_gb_content_width":"","footnotes":""},"categories":[12,14,9,16,20],"tags":[],"class_list":["post-122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion","category-generacion-energia","category-noticias","category-sistemas-de-monitorizacion-en-continuo","category-sistemas-de-supervision-analisis-y-diagnostico"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"TSI SL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"T\u00e9cnicas y Servicios de Ingenier\u00eda - Servicios de ingenier\u00eda de ruido y vibraciones.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda\" \/>\n\t\t<meta property=\"og:description\" content=\"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-04-02T14:23:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-04-11T11:45:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@tsisl_oficial\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@tsisl_oficial\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#blogposting\",\"name\":\"La Central Nuclear de ALmaraz conf\\u00eda a TSI la especializaci\\u00f3n de sus t\\u00e9cnicos de ingenier\\u00eda de resultados en vibraciones, mantenimiento basado en condici\\u00f3n y sistemas de monitorizaci\\u00f3n. - T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"headline\":\"La Central Nuclear de ALmaraz conf\\u00eda a TSI la especializaci\\u00f3n de sus t\\u00e9cnicos de ingenier\\u00eda de resultados en vibraciones, mantenimiento basado en condici\\u00f3n y sistemas de monitorizaci\\u00f3n.\",\"author\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/tsitsisl-es\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tsisl.es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cna1.jpg\",\"width\":612,\"height\":335,\"caption\":\"Central Nuclear Espa\\u00f1a\"},\"datePublished\":\"2013-04-02T14:23:48+02:00\",\"dateModified\":\"2022-04-11T13:45:31+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#webpage\"},\"articleSection\":\"Formaci\\u00f3n, Generaci\\u00f3n energ\\u00eda., Noticias, Sistemas de Monitorizaci\\u00f3n en Continuo, Sistemas de Supervisi\\u00f3n, An\\u00e1lisis y Diagn\\u00f3stico, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#listItem\",\"name\":\"La Central Nuclear de ALmaraz conf\\u00eda a TSI la especializaci\\u00f3n de sus t\\u00e9cnicos de ingenier\\u00eda de resultados en vibraciones, mantenimiento basado en condici\\u00f3n y sistemas de monitorizaci\\u00f3n.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#listItem\",\"position\":3,\"name\":\"La Central Nuclear de ALmaraz conf\\u00eda a TSI la especializaci\\u00f3n de sus t\\u00e9cnicos de ingenier\\u00eda de resultados en vibraciones, mantenimiento basado en condici\\u00f3n y sistemas de monitorizaci\\u00f3n.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\",\"name\":\"T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Servicios de ingenier\\u00eda de ruido y vibraciones.\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/tsisl_oficial\",\"https:\\\/\\\/www.youtube.com\\\/@tsisl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/2298820\\\/admin\\\/feed\\\/posts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/tsitsisl-es\\\/#author\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/tsitsisl-es\\\/\",\"name\":\"TSI SL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f0417e3f129b691a3c9ab028644dbf02faaae5b581cac7d5fdb9493505df6e2a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"TSI SL\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#webpage\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/\",\"name\":\"La Central Nuclear de ALmaraz conf\\u00eda a TSI la especializaci\\u00f3n de sus t\\u00e9cnicos de ingenier\\u00eda de resultados en vibraciones, mantenimiento basado en condici\\u00f3n y sistemas de monitorizaci\\u00f3n. - T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Durante los d\\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \\u201cCurso de Especializaci\\u00f3n en Vibraciones, Mantenimiento Basado en Condici\\u00f3n y Sistemas de Monitorizaci\\u00f3n\\u201d, dirigido al grupo de T\\u00e9cnicos Medios del departamento de Ingenier\\u00eda de Resultados de la CENTRAL NUCLEAR DE\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/tsitsisl-es\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/author\\\/tsitsisl-es\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/tsisl.es\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/cna1.jpg\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#mainImage\",\"width\":612,\"height\":335,\"caption\":\"Central Nuclear Espa\\u00f1a\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/2013\\\/04\\\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\\\/#mainImage\"},\"datePublished\":\"2013-04-02T14:23:48+02:00\",\"dateModified\":\"2022-04-11T13:45:31+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tsisl.es\\\/es\\\/\",\"name\":\"T\\u00e9cnicas y Servicios de Ingenier\\u00eda\",\"description\":\"Servicios de ingenier\\u00eda de ruido y vibraciones.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsisl.es\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE","canonical_url":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#blogposting","name":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda","headline":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n.","author":{"@id":"https:\/\/tsisl.es\/es\/author\/tsitsisl-es\/#author"},"publisher":{"@id":"https:\/\/tsisl.es\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/cna1.jpg","width":612,"height":335,"caption":"Central Nuclear Espa\u00f1a"},"datePublished":"2013-04-02T14:23:48+02:00","dateModified":"2022-04-11T13:45:31+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#webpage"},"isPartOf":{"@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#webpage"},"articleSection":"Formaci\u00f3n, Generaci\u00f3n energ\u00eda., Noticias, Sistemas de Monitorizaci\u00f3n en Continuo, Sistemas de Supervisi\u00f3n, An\u00e1lisis y Diagn\u00f3stico, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/#listItem","position":1,"name":"Inicio","item":"https:\/\/tsisl.es\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/tsisl.es\/es\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#listItem","name":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n."},"previousItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#listItem","position":3,"name":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n.","previousItem":{"@type":"ListItem","@id":"https:\/\/tsisl.es\/es\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/tsisl.es\/es\/#organization","name":"T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Servicios de ingenier\u00eda de ruido y vibraciones.","url":"https:\/\/tsisl.es\/es\/","sameAs":["https:\/\/twitter.com\/tsisl_oficial","https:\/\/www.youtube.com\/@tsisl","https:\/\/www.linkedin.com\/company\/2298820\/admin\/feed\/posts\/"]},{"@type":"Person","@id":"https:\/\/tsisl.es\/es\/author\/tsitsisl-es\/#author","url":"https:\/\/tsisl.es\/es\/author\/tsitsisl-es\/","name":"TSI SL","image":{"@type":"ImageObject","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f0417e3f129b691a3c9ab028644dbf02faaae5b581cac7d5fdb9493505df6e2a?s=96&d=mm&r=g","width":96,"height":96,"caption":"TSI SL"}},{"@type":"WebPage","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#webpage","url":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/","name":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/tsisl.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#breadcrumblist"},"author":{"@id":"https:\/\/tsisl.es\/es\/author\/tsitsisl-es\/#author"},"creator":{"@id":"https:\/\/tsisl.es\/es\/author\/tsitsisl-es\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/tsisl.es\/wp-content\/uploads\/2021\/08\/cna1.jpg","@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#mainImage","width":612,"height":335,"caption":"Central Nuclear Espa\u00f1a"},"primaryImageOfPage":{"@id":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/#mainImage"},"datePublished":"2013-04-02T14:23:48+02:00","dateModified":"2022-04-11T13:45:31+02:00"},{"@type":"WebSite","@id":"https:\/\/tsisl.es\/es\/#website","url":"https:\/\/tsisl.es\/es\/","name":"T\u00e9cnicas y Servicios de Ingenier\u00eda","description":"Servicios de ingenier\u00eda de ruido y vibraciones.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/tsisl.es\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"T\u00e9cnicas y Servicios de Ingenier\u00eda - Servicios de ingenier\u00eda de ruido y vibraciones.","og:type":"article","og:title":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda","og:description":"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE","og:url":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/","og:image":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg","og:image:secure_url":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg","og:image:width":500,"og:image:height":500,"article:published_time":"2013-04-02T14:23:48+00:00","article:modified_time":"2022-04-11T11:45:31+00:00","twitter:card":"summary","twitter:site":"@tsisl_oficial","twitter:title":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n. - T\u00e9cnicas y Servicios de Ingenier\u00eda","twitter:description":"Durante los d\u00edas 25 a 27 de Febrero y 4 a 5 de Marzo de 2013, se ha impartido en la instalaciones de TSI, el \u201cCurso de Especializaci\u00f3n en Vibraciones, Mantenimiento Basado en Condici\u00f3n y Sistemas de Monitorizaci\u00f3n\u201d, dirigido al grupo de T\u00e9cnicos Medios del departamento de Ingenier\u00eda de Resultados de la CENTRAL NUCLEAR DE","twitter:creator":"@tsisl_oficial","twitter:image":"https:\/\/tsisl.es\/wp-content\/uploads\/2024\/01\/logo_miniatura.jpg"},"aioseo_meta_data":{"post_id":"122","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-08-06 11:37:23","updated":"2025-06-05 10:31:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tsisl.es\/es\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tsisl.es\/es\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/tsisl.es\/es\/"},{"label":"Noticias","link":"https:\/\/tsisl.es\/es\/category\/noticias\/"},{"label":"La Central Nuclear de ALmaraz conf\u00eda a TSI la especializaci\u00f3n de sus t\u00e9cnicos de ingenier\u00eda de resultados en vibraciones, mantenimiento basado en condici\u00f3n y sistemas de monitorizaci\u00f3n.","link":"https:\/\/tsisl.es\/es\/2013\/04\/la-central-nuclear-de-almaraz-confia-a-tsi-la-especializacion-de-sus-tecnicos-de-ingenieria-de-resultados-en-vibraciones-mantenimiento-basado-en-condicion-y-sistemas-de-monitorizacion\/"}],"_links":{"self":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":3,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"predecessor-version":[{"id":36463,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/posts\/122\/revisions\/36463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/media\/6"}],"wp:attachment":[{"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsisl.es\/es\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}